{"id":2248,"date":"2021-11-23T20:30:51","date_gmt":"2021-11-23T19:30:51","guid":{"rendered":"https:\/\/jadastroom.nl\/?post_type=product&#038;p=2248"},"modified":"2026-02-25T10:59:40","modified_gmt":"2026-02-25T09:59:40","slug":"victron-agm-accu-12v-90ah","status":"publish","type":"product","link":"https:\/\/www.jadastroom.nl\/es\/winkel\/accus\/victron-agm-accu-12v-90ah\/","title":{"rendered":"Bater\u00eda AGM Victron 12V \/ 90Ah"},"content":{"rendered":"<div class=\"sku\">N\u00famero de art\u00edculo: BAT412800084<\/div>\n<div class=\"long-description with-long open\">\n<div class=\"std\">\n<div class=\"shortdesc active\">\n<p class=\"translation-block\">Bater\u00eda Victron AGM 12V\/90Ah Deep Cycle equipada con conexiones planas de cobre con orificios para tornillos M8 para garantizar el mejor contacto posible y sin necesidad de bornes de bater\u00eda.<\/p>\n<p><strong>Algemene specificaties<\/strong>:<br \/>\nTecnolog\u00eda: AGM<br \/>\nCapacidad nominal de la bater\u00eda (Ah)*: 90<br \/>\nVoltaje de la bater\u00eda (V): 12<br \/>\nConexi\u00f3n: cobre<br \/>\nDimensiones LxAnxAl (mm): 350 x 167 x 183<br \/>\nPeso (kg): 27<br \/>\nCCA&lt; @0\u00b0F: 400<br \/>\nRES CAP @80\u00b0F: 130<\/p>\n<p>* Capacidad nominal: descarga en 20 horas a 25\u00b0C<\/p>\n<\/div>\n<div class=\"longdesc\">\n<p class=\"translation-block\">La bater\u00eda Victron 12V\/90Ah AGM es una bater\u00eda sellada con una capacidad de 90Ah basada en la tecnolog\u00eda VRLA. Una bater\u00eda AGM tambi\u00e9n se denomina bater\u00eda multiuso o de doble prop\u00f3sito y es adecuada tanto para descargas lentas como para la entrega de altas corrientes durante per\u00edodos cortos, para inversores, h\u00e9lices de proa y cabrestantes. Las conexiones de la bater\u00eda son de cobre con orificios para tornillos M6 para garantizar un buen contacto. Los terminales de cable prensados pueden montarse directamente en la bater\u00eda y no se necesitan bornes adicionales. Las bater\u00edas cumplen con las especificaciones europeas CE y estadounidenses UL en carcasas de ABS ign\u00edfugas y se suministran con la garant\u00eda mundial de 2 a\u00f1os de Victron Energy.<\/p>\n<p><strong>AGM significa Absorbed Glass Mat.<\/strong><br \/>\nEn las bater\u00edas AGM, el electrolito est\u00e1 absorbido en una estera de fibra de vidrio que est\u00e1 sujeta entre las placas. En una bater\u00eda AGM, los portadores de carga, los iones de hidr\u00f3geno (H\u2082) y los iones sulfato (SO\u2084), se desplazan m\u00e1s f\u00e1cilmente entre las placas que en una bater\u00eda de gel.<\/p>\n<p><strong>Tecnolog\u00eda VRLA<\/strong><br \/>\nVRLA significa Valve Regulated Lead Acid. Esto significa que las bater\u00edas est\u00e1n selladas. Solo en caso de una carga incorrecta y\/o celdas defectuosas puede escapar gas a trav\u00e9s de una v\u00e1lvula de seguridad. Las bater\u00edas VRLA no requieren mantenimiento durante toda su vida \u00fatil.<\/p>\n<p><strong>Baja autodescarga<\/strong><br \/>\nGracias al uso de rejillas de plomo-calcio y materiales muy puros, las bater\u00edas VRLA de Victron pueden soportar largos periodos sin carga sin problemas. La autodescarga es inferior al 2 % por mes a una temperatura de 20 \u00b0C. Esta tasa se duplica por cada aumento de temperatura de 10 \u00b0C. Las bater\u00edas VRLA de Victron pueden almacenarse hasta un a\u00f1o sin necesidad de recargarlas, siempre que se mantengan a una temperatura relativamente baja.<\/p>\n<p><strong>Recuperaci\u00f3n excepcional tras la descarga<\/strong><\/p>\n<p>Las bater\u00edas VRLA de Victron se recuperan muy bien, incluso despu\u00e9s de descargas profundas y prolongadas. No obstante, las descargas profundas y repetidas tienen un impacto negativo en la vida \u00fatil de todas las bater\u00edas de plomo-\u00e1cido. Las bater\u00edas Victron no son una excepci\u00f3n.<\/p>\n<p><strong>Caracter\u00edsticas de descarga de la bater\u00eda<\/strong><br \/>\nLa capacidad nominal de las bater\u00edas Victron \u00abDeep Cycle\u00bb se refiere a una descarga de 20 horas (corriente de descarga de 0,05C). La capacidad nominal de las bater\u00edas Victron Tubular Plate Long Life se refiere a una descarga de 10 horas. La capacidad efectiva disminuye a medida que aumenta la corriente de descarga.<\/p>\n<p><strong>Corriente de carga<\/strong><br \/>\nLa corriente de carga de una bater\u00eda VRLA no debe superar 0,2C (20A para una bater\u00eda de 100 Ah). La temperatura de la bater\u00eda aumentar\u00e1 en m\u00e1s de 10 \u00b0C si la corriente de carga supera 0,2C, y entonces es necesaria la compensaci\u00f3n de temperatura.<\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Artikelnummer:\u00a0BAT412800084 Victron AGM 12V\/90Ah Deep Cycle accu\u00a0voorzien van met platte koperen aansluitingen met gaten voor M8 bouten om een zo best mogelijk contact te waarborgen en accupolen niet nodig zijn. Algemene specificaties: Technologie: vlakke plaat AGM Nominale accucapaciteit (Ah)*: 90 Accuspanning (V): 12 Aansluiting: koper Afmetingen LxBxH (mm): 350 x 167 x 183 Gewicht (kg): [&hellip;]<\/p>\n","protected":false},"featured_media":3870,"comment_status":"open","ping_status":"closed","template":"","meta":{"wds_primary_product_brand":0,"wds_primary_product_cat":140},"product_brand":[],"product_cat":[140],"product_tag":[],"class_list":["post-2248","product","type-product","status-publish","has-post-thumbnail","product_cat-accus","pa_ah-accu-90-ah","pa_merk-accu-victron-energy","pa_type-accu-agm","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.jadastroom.nl\/es\/wp-json\/wp\/v2\/product\/2248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jadastroom.nl\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.jadastroom.nl\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jadastroom.nl\/es\/wp-json\/wp\/v2\/comments?post=2248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jadastroom.nl\/es\/wp-json\/wp\/v2\/media\/3870"}],"wp:attachment":[{"href":"https:\/\/www.jadastroom.nl\/es\/wp-json\/wp\/v2\/media?parent=2248"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.jadastroom.nl\/es\/wp-json\/wp\/v2\/product_brand?post=2248"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.jadastroom.nl\/es\/wp-json\/wp\/v2\/product_cat?post=2248"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.jadastroom.nl\/es\/wp-json\/wp\/v2\/product_tag?post=2248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}